{"id":1409,"date":"2020-03-23T10:00:02","date_gmt":"2020-03-23T09:00:02","guid":{"rendered":"https:\/\/comsentido.es\/?p=1409"},"modified":"2024-03-07T12:01:51","modified_gmt":"2024-03-07T11:01:51","slug":"la-importancia-del-blog-en-la-estrategia-de-marketing-de-tu-empresa","status":"publish","type":"post","link":"https:\/\/comsentido.es\/ca\/la-importancia-del-blog-en-la-estrategia-de-marketing-de-tu-empresa\/","title":{"rendered":"La importancia del blog en la estrategia de marketing de tu empresa"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>La creaci\u00f3n de un blog corporativo es una herramienta clave en la estrategia de marketing de tu empresa para posicionar tu marca. Mar\u00eda, del blog Decoraci\u00f3n y Cer\u00e1mica te cuenta por qu\u00e9 en este post.<\/p>\n<p><!--more--><\/p>\n<p>Actualmente es muy importante para una empresa <strong>disponer de una p\u00e1gina web bien estructurada y con toda la informaci\u00f3n que el usuario pueda necesitar al alcance de unos pocos clicks<\/strong>, ya que internet se ha convertido en un enorme escaparate que puede conseguir que tu empresa traspase fronteras. Por otro lado, estas facilidades tambi\u00e9n afectar\u00e1n de la misma manera a tu competencia, siendo \u00e9sta ahora mayor y a un nivel mucho m\u00e1s global.<\/p>\n<p>Y es en este sentido, donde cobra much\u00edsimo valor tener un buen blog y unas redes sociales bien cuidadas.<\/p>\n<h2>\u00bfPor qu\u00e9 un blog es importante para una web de empresa?<\/h2>\n<p>En una <strong>p\u00e1gina web corporativo solemos mostrar nuestros productos, nuestros logros, proyectos\u2026<\/strong>pero siempre de un modo m\u00e1s o menos comercial a modo de escaparate. De este modo, se podr\u00eda comparar una tienda f\u00edsica con una virtual, puesto que, al igual que cuando paseamos por la ciudad y encontramos un escaparate que por alg\u00fan motivo llama nuestra atenci\u00f3n, nos detendremos frente a \u00e9l a observar qu\u00e9 tiene y, si algo nos interesa, entraremos en su interior para ver y conocer un poco m\u00e1s.<\/p>\n<p>En el caso de qu\u00e9 decidas entrar en la tienda, por inercia mirar\u00e1s hacia arriba <strong>buscando su nombre y logotipo para saber qui\u00e9n es, \u00bfno?<\/strong> Pues ese momento, crucial en muchas ocasiones, <strong>en una tienda virtual ser\u00eda el \u201cMomento Blog\u201d,<\/strong> donde desde el punto de vista de la empresa, podremos <strong>mostrar nuestro \u201cyo\u201d m\u00e1s humano<\/strong> y dejar que nuestros clientes nos conozcan \u201cpersonalmente\u201d, puesto que, al final, a todos nos gusta conocer a las personas que hay detr\u00e1s atendi\u00e9ndonos.<\/p>\n<p>Por todo ello, <strong>incorporar un blog en la estrategia comercial de la empresa es crucial,<\/strong> pero&#8230;<\/p>\n<h2>\u00bfQu\u00e9 consideraciones deber\u00edamos tener en cuenta?<\/h2>\n<h4>1. REPUTACI\u00d3N ONLINE<\/h4>\n<p>Un blog influir\u00e1 en tu reputaci\u00f3n online y como consecuencia, en la de tu empresa, por lo que deber\u00e1s tratar de mostrar siempre <strong>contenido veraz y en consonancia con tu tem\u00e1tica.<\/strong><\/p>\n<h4>2. CONFIANZA Y CERCAN\u00cdA<\/h4>\n<p>\u00c9ste es un punto muy importante debido a que <strong>a trav\u00e9s del blog tus clientes y lectores pueden conocerte mejor,<\/strong> empatizar contigo y saber qui\u00e9n hay detr\u00e1s de la empresa y, por tanto te convertir\u00e1s en ese \u201cconocido de confianza\u201d a quien dirigirse en caso de duda o necesidad. Por ello, ser\u00e1 muy importante que <strong>contestes a todos los emails y comentarios de tus lectores con la mayor brevedad posible.<\/strong><\/p>\n<h4>3. CONTENIDO<\/h4>\n<p>Deber\u00e1s plantearte \u00bfescribo para Google o para mi lector? Lo m\u00e1s importante para un blog, es <strong>escribir contenido original y de calidad,<\/strong> que nos identifique, utilizando siempre nuestras propias palabras o el estilo que mejor nos defina, tratando de ofrecer un post que aporte valor a nuestros lectores, eso s\u00ed sin olvidarnos del SEO. Lo que tampoco se puede hacer y es bastante habitual, es crear post con titulares llamativos cuyo texto est\u00e9 tan preparado para el SEO y que luego su contenido no ofrezca el valor esperado.<\/p>\n<h4>4. \u00bfA QUI\u00c9N ME DIRIJO?<\/h4>\n<p>Muy importante saber para qui\u00e9n escribo, es decir, <strong>\u00bfqui\u00e9n es mi cliente potencial?<\/strong> Puesto que seg\u00fan a qui\u00e9n me dirija utilizar\u00e9 un lenguaje m\u00e1s coloquial o m\u00e1s formal. Si buscamos un blog m\u00e1s profesional y que aporte contenido y valor a la empresa, utilizar un lenguaje formal y correcto, donde expresemos nuestras opiniones, consejos y valoraciones sobre los temas que nos incumben guardando siempre las formas y buenos modales.<\/p>\n<h4>5. CONSTANCIA<\/h4>\n<p><strong>Un blog no ofrece resultados de hoy para ma\u00f1ana,<\/strong> sino que como muchos dicen, es una carrera de fondo, en la que debes ser constante y no desanimarte por no ver resultados inmediatos, pero con dedicaci\u00f3n, tiempo y constancia seguro que llegar\u00e1s a buen puerto.<\/p>\n<h2>Tipos de blogs corporativos<\/h2>\n<p><strong>Si te estas planteando crear un blog en tu empresa existen varios modos por los que decantarte:<\/strong><\/p>\n<ul>\n<li><strong>Blog profesional siendo la empresa quien \u201chabla\u201d<\/strong> y con una estrategia m\u00e1s directa y comercial.<\/li>\n<li><strong>Blog profesional<\/strong> dentro del mismo dominio<strong> pero poniendo nombre y apellido al autor de cada post,<\/strong> creando de este modo profesionalidad y cercan\u00eda con el lector, a la vez que permite conocer al personal de la empresa.<\/li>\n<li><strong>Blog profesional<\/strong> dentro del mismo dominio siendo un profesional del marketing o <strong>redactor quien escribe los posts y present\u00e1ndose como tal.<\/strong><\/li>\n<li><strong>Blog m\u00e1s personal con dominio diferente al de la empresa<\/strong> pero vinculado por proximidad entre blogger y empresa. \u00c9sta opci\u00f3n suele ocurrir muy a menudo en las pymes familiares en los que todo el personal posee un v\u00ednculo con la empresa.<\/li>\n<\/ul>\n<p>Adem\u00e1s, si est\u00e1s comenzando y deseas<a href=\"https:\/\/www.hubspot.es\/products\/cms\/free-blog-maker\" target=\"_blank\" rel=\"noopener\"> hacer un blog gratis<\/a>, existen plataformas que te permiten crear y gestionar tu blog sin coste alguno, lo cual puede ser una excelente manera de empezar a construir tu presencia en l\u00ednea sin invertir en un dominio propio. Elegir la opci\u00f3n correcta depender\u00e1 de tus objetivos, recursos y el nivel de personalizaci\u00f3n que desees para tu blog.<\/p>\n<p>Seguro que conocer\u00e9is blogs con todas las opciones arriba descritas, y en mi caso, por ejemplo, me decant\u00e9 por crear un <a href=\"http:\/\/www.decoracionyceramica.com\">blog m\u00edo personal,<\/a> donde hablo acerca de lo que vivo, conozco y descubro en el d\u00eda a d\u00eda de mi trabajo en mi empresa familiar Cenemar Cer\u00e1micas.<\/p>\n<p>Me decid\u00ed por esta opci\u00f3n, despu\u00e9s de probar el blog profesional, porque era donde me sent\u00eda m\u00e1s c\u00f3moda, pudiendo hablar de temas, siempre relacionados con la cer\u00e1mica, la decoraci\u00f3n y el interiorismo, desde un punto de vista m\u00e1s personal y no tan vinculante a Cenemar, tratando diferentes aspectos del mundo cer\u00e1mico tanto concernientes a proveedores de mi empresa como a aquellos que no lo son. En definitiva, pens\u00e9 que siendo yo misma quien hablaba y firmaba cada post, ten\u00eda m\u00e1s libertad para expresar mi opini\u00f3n.<\/p>\n<p>As\u00ed, si buscas crear un blog para tu empresa, busca la opci\u00f3n con la mejor te sientas y m\u00e1s te identifiques, pero elijas la que elijas, estoy segura de que <strong>con dedicaci\u00f3n, tiempo y constancia, un blog siempre te ayudar\u00e1 en la estrategia de tu empresa.<\/strong><\/p>\n<h4><strong>La invitada de hoy es&#8230;<\/strong><\/h4>\n<p>Mi nombre es Mar\u00eda, del blog <a href=\"http:\/\/www.decoracionyceramica.com\">Decoraci\u00f3n y Cer\u00e1mica,<\/a> un espacio en el que comparto mis inquietudes sobre la decoraci\u00f3n y la cer\u00e1mica, sobre los diversos usos y caracter\u00edsticas de este material, muchas veces desconocido, pero que posee multitud de cualidades para la decoraci\u00f3n, restauraci\u00f3n de edificios antiguos, higiene en laboratorios\u2026 y un sinf\u00edn de posibilidades m\u00e1s. Pod\u00e9is contactar conmigo en maria@decoracionyceramica.com , a trav\u00e9s de Facebook , Twitter o Linkedin<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La creaci\u00f3n de un blog corporativo es una herramienta clave en la estrategia de marketing de tu empresa para posicionar tu marca. Mar\u00eda, del blog Decoraci\u00f3n y Cer\u00e1mica te cuenta por qu\u00e9 en este post.<\/p>\n","protected":false},"author":3,"featured_media":2804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6],"tags":[101,338,339,14,121,10,327,301,331],"class_list":["post-1409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing","tag-agencia-de-marketing","tag-blog","tag-blog-corporativo","tag-comsentido","tag-marketing","tag-marketing-digital","tag-pagina-web","tag-posicionamiento-web","tag-web-copywriting"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/posts\/1409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/comments?post=1409"}],"version-history":[{"count":0,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/posts\/1409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/media\/2804"}],"wp:attachment":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/media?parent=1409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/categories?post=1409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/tags?post=1409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}