{"id":1132,"date":"2019-10-24T18:17:55","date_gmt":"2019-10-24T16:17:55","guid":{"rendered":"http:\/\/comsentido.es\/?p=1132"},"modified":"2024-02-27T09:38:54","modified_gmt":"2024-02-27T08:38:54","slug":"10-trucos-para-que-google-indexe-tu-web","status":"publish","type":"post","link":"https:\/\/comsentido.es\/ca\/10-trucos-para-que-google-indexe-tu-web\/","title":{"rendered":"10 trucos para que Google indexe tu web"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Tienes una web perfecta (o eso crees) pero nadie llega a ella porque no atraes tr\u00e1fico org\u00e1nico, es decir, nunca apareces en Google. Tienes un serio problema con el SEO y hay que solucionarlo. Aqu\u00ed encontrar\u00e1s 10 trucos o consejos que te ayudar\u00e1n a ponerle remedio.<\/p>\n<p><!--more--><\/p>\n<h2>\u00bfPor qu\u00e9 la gente no encuentra mi web en Google?<\/h2>\n<p>Consigas que tus seguidores de redes sociales entren a tu web pero<strong> no atraes a nuevos visitantes porque tu web no aparece en Google.<\/strong> <strong>El tr\u00e1fico org\u00e1nico es una de las mejores formas de atraer nuevos clientes a tu sitio web<\/strong> pero tienes que tener una web optimizada para que Google la entienda correctamente y te la posicione como toque.<\/p>\n<p>No hace falta invertir grandes cantidades en agencias de SEO o en publicidad SEM, pero s\u00ed que <strong>debes invertir mucho tiempo en los <a href=\"https:\/\/comsentido.es\/marketing-digital\/diseno-paginas-web-y-ecommerces\/\" target=\"_blank\" rel=\"noopener noreferrer\">contenidos de tu web<\/a> y en cuidar al m\u00e1ximo al SEO.<\/strong><\/p>\n<h2>\u00bfC\u00f3mo puedo posicionarme en Google?<\/h2>\n<h4>1. Informaci\u00f3n de calidad e inter\u00e9s<\/h4>\n<p><strong>Lo m\u00e1s importante, no solo para Google, si no para tu audiencia, es el contenido de tu p\u00e1gina web y la calidad de los textos. <\/strong>Por ello es muy importante que <strong>dejes la redacci\u00f3n de los textos de tu p\u00e1gina web en manos de profesionales<\/strong> para conseguir un buen <a href=\"https:\/\/comsentido.es\/marketing-digital\/diseno-paginas-web-y-ecommerces\/\">web copywriting<\/a> y una escritura pensando en el SEO de tu web y lo que tu cliente quiere encontrar en ella. \u2764<\/p>\n<h4>2. Blog activo y con contenido que aporte valor<\/h4>\n<p>Una de las actividades m\u00e1s sencillas que puedas hacer para mantener tu web activa y con nuevas p\u00e1ginas de manera constante es tener un buen blog.\u00a0<strong>\u00bfQu\u00e9 es un buen blog?\u00a0<\/strong>Es aquel que se escribe con regularidad, el contenido aporta valor, no copias si no que escribes de forma \u00fanica, tienes mimo y cuidado con la ortograf\u00eda&#8230;<\/p>\n<p>Tambi\u00e9n<strong> debes tener muy presentes los temas sobre los que escribes,<\/strong> teniendo en cuenta que sean temas recurrentes que tus clientes potenciales puedan estar buscando informaci\u00f3n y, tambi\u00e9n sin olvidar el calendario editorial de cada mes basado en temas trending topic. El <a href=\"http:\/\/shop.comsentido.es\/tienda\/marketing\" target=\"_blank\" rel=\"noopener noreferrer\">calendario del community manager<\/a> puede ayudarte a encontrar los temas id\u00f3neos para cada semana del a\u00f1o.<\/p>\n<h4>3. Linkbuilding: enlaces de calidad, internos y externos<\/h4>\n<p>Seguro que no es la primera vez que lo oyes, pero enlazar es la clave. <strong>Es muy importante que conectes las diferentes p\u00e1ginas de tu web entre ellas:<\/strong> del blog a p\u00e1ginas est\u00e1ticas de servicios, de la home a una p\u00e1gina espec\u00edfica&#8230; y tambi\u00e9n, si es necesario, enlaces a otros sitios web de inter\u00e9s para tu audiencia.<\/p>\n<p>Adem\u00e1s, un buen truco para mejorar<strong> el posicionamiento de tu web es conseguir enlaces a tu p\u00e1gina en otras webs.<\/strong> Esto<strong> puedes conseguirlo de manera gratuita a trav\u00e9s del guest blogging<\/strong>, es decir, intercambios de art\u00edculos de expertos invitados en tu blog. \u00a1Ganar\u00e1s en contenido de calidad y en enlaces de inter\u00e9s!<\/p>\n<p>Tambi\u00e9n puedes comprar enlaces en otras webs pero debes asegurarte que sean de calidad y no directorios o estafas. Eso s\u00ed, mi recomendaci\u00f3n es que no compres, que los consigas con tu esfuerzo y tendr\u00e1s mejores resultados.<\/p>\n<p><strong>\u00a1Acu\u00e9rdate de poner que los enlaces se abran en otra p\u00e1gina!<\/strong> Especialmente cuando diriges a otras web, si no perder\u00e1s a ese visitante y quiz\u00e1s no vuelva nunca jam\u00e1s \ud83d\ude22<\/p>\n<h4>4. Optimiza los t\u00edtulos<\/h4>\n<p><strong>Construye t\u00edtulos de calidad, adaptados a las b\u00fasquedas m\u00e1s populares en tu regi\u00f3n y de esa tem\u00e1tica.<\/strong> Puedes ayudarte de herramientas como <a href=\"https:\/\/www.semrush.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">SemRush<\/a>, <a href=\"https:\/\/trends.google.es\/trends\/\" target=\"_blank\" rel=\"noopener noreferrer\">Google Trends<\/a> o <a href=\"https:\/\/keywordtool.io\/es\" target=\"_blank\" rel=\"noopener noreferrer\">Keyword Tool<\/a>.<\/p>\n<p>Es importante que <strong>escojas t\u00edtulos atractivos y cortos, pero que sean descriptivos del contenido que van a encontrar<\/strong> dentro de tu blog o tu web.<\/p>\n<p><strong>Tambi\u00e9n debes crear t\u00edtulos H2, H3 y H4 dentro del contenido de la web\u00a0 o de los posts del blog,<\/strong> ayudando a que Google valore cu\u00e1l es el contenido m\u00e1s interesante de tu p\u00e1gina web y para que lo entienda correctamente.<\/p>\n<h4>5. Indexa s\u00f3lo los contenidos que quieras que aparezcan en Google<\/h4>\n<p><strong>Aprov\u00e9chate de las herramientas &#8220;no index&#8221; para que Google no rastree las p\u00e1ginas que no te interesan que aparezcan en buscadores.<\/strong> Estas p\u00e1ginas pueden ser las de error, en reformas, p\u00e1ginas sin contenido.<\/p>\n<p>Es importante que elimines estas p\u00e1ginas de la indexaci\u00f3n para que no te penalicen al resto que tienes correctamente hechas: textos, dise\u00f1o y optimizaci\u00f3n SEO. <strong>\u00a1Para Google todo cuenta!<\/strong> As\u00ed que no pierdas puntos, ense\u00f1\u00e1ndole p\u00e1ginas de tu web que no son buenas.<\/p>\n<h4>6. Optimiza el SEO de tu web con un pluggin<\/h4>\n<p>Es importante que a cada p\u00e1gina y a cada entrada le <strong>a\u00f1adas la informaci\u00f3n clave como t\u00edtulo, descripci\u00f3n, palabras clave, imagen de portada, optimizaci\u00f3n para RRSS.<\/strong> Todo esto <strong>puedes conseguirlo de forma sencilla con alg\u00fan pluggin,<\/strong> yo te recomiendo para wordpress &#8220;All in One SEO&#8221;, ya que cuentas con una versi\u00f3n gratuita que te permite mejorar tu sitio web de forma f\u00e1cil e intuitiva.<\/p>\n<h4>7. No olvides utilizar las palabras clave<\/h4>\n<p>Crea listados de palabras clave para cada p\u00e1gina de tu sitio web y para cada entrada de tu blog y haz buen uso de ellas. <strong>Busca palabras mejor posicionado y \u00fasalas en tu texto de manera coherente, adem\u00e1s puedes ayudarte de utilizar sin\u00f3nimos y frases con significado similar.\u00a0<\/strong><\/p>\n<p>Actualmente las palabras clave que mejor funcionan son las <strong>long tails,<\/strong> as\u00ed que no olvides hacer uso de ellas. Adem\u00e1s, debes tener en cuenta del a<strong>uge de las b\u00fasquedas por voz y adaptar el contenido<\/strong> a esta nueva forma de buscar informaci\u00f3n en internet.<\/p>\n<h4>8. Nombra correctamente todas las im\u00e1genes<\/h4>\n<p>Te recomiendo que <strong>guardes la imagen en tu ordenador\/m\u00f3vil con un nombre correcto,<\/strong> por ejemplo, yo uso t\u00edtulo + marca. Esto significar\u00eda que la imagen de este post lleva el t\u00edtulo de &#8220;Gu\u00eda posicionamiento e indexaci\u00f3n Google_coMsentido&#8221;. Esto har\u00e1 que si alguien se descarga la imagen te ahorres t\u00edtulos c\u00f3mo: La_\u00faltima_versi\u00f3n_final_final_horrible_final_de_verdad o cosas peores&#8230;<\/p>\n<p>Tambi\u00e9n debes asegurarte de que tenga <strong>el atributo de t\u00edtulo a\u00f1adido una vez subida a tu web,<\/strong> que podr\u00eda servirte el mismo formato anterior. De esta forma Google tambi\u00e9n indexar\u00e1 tus im\u00e1genes. \u00a1La b\u00fasqueda por im\u00e1genes es clave!<\/p>\n<h4>9.\u00a0 Crea un mapa .xml<\/h4>\n<p><strong>Crear un mapa de tu sitio web es una forma de ayudar a Google a entender la estructura de tu p\u00e1gina<\/strong>. Esto le facilita el trabajo y ayuda a posicionarlo correctamente y a que rastree todas las p\u00e1ginas de tu web. Con el pluggin de SEO que te he recomendado anteriormente, puedes crear f\u00e1cilmente el tuyo.<\/p>\n<p>Adem\u00e1s, te recomiendo que<strong> cada vez que crees una p\u00e1gina nueva la a\u00f1adas a la herramienta <a href=\"https:\/\/search.google.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Search Console de Google<\/a><\/strong> para que la rastree lo antes posible. \u26a1<\/p>\n<p>\u00a1Acu\u00e9rdate de revisar que no aparecen las p\u00e1ginas que no quieras que sean rastreadas!<\/p>\n<h4>10. Acu\u00e9rdate de crear URL amigables<\/h4>\n<p>Y ya por \u00faltimo, ten en cuenta las url de tu web. Olv\u00eddate de las que se generan autom\u00e1ticamente con un n\u00famero, fecha o caracteres aleatorios y \u00a1trab\u00e1jalas! <strong>Crea url personalizadas y descriptivas y eso mejorar\u00e1 el SEO de tu web<\/strong> y ayudar\u00e1 a su posicionamiento en los buscadores.<\/p>\n<h4>Y lo m\u00e1s importante, fideliza a tus usuarios. \u00a1Haz que repitan!<\/h4>\n<p><strong>Si adem\u00e1s de atraer a nuevos usuarios, consigues que tus visitantes repitan&#8230; \u00a1triunfar\u00e1s! Y para ello s\u00f3lo necesitas tener la mejor web:<\/strong> optimizada, con buenos textos, contenido de valor, atractiva y con especial atenci\u00f3n a la usabilidad y adaptaci\u00f3n a todos los dispositivos.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfTe ha gustado este post? \u00bfTienes alg\u00fan truco que quieras compartir? Cu\u00e9ntamelo en los comentarios \ud83d\ude0d<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tienes una web perfecta (o eso crees) pero nadie llega a ella porque no atraes tr\u00e1fico org\u00e1nico, es decir, nunca apareces en Google. Tienes un serio problema con el SEO y hay que solucionarlo. Aqu\u00ed encontrar\u00e1s 10 trucos o consejos que te ayudar\u00e1n a ponerle remedio.<\/p>\n","protected":false},"author":3,"featured_media":2767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[6],"tags":[101,14,44,121,10,301],"class_list":["post-1132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing","tag-agencia-de-marketing","tag-comsentido","tag-comunicacion","tag-marketing","tag-marketing-digital","tag-posicionamiento-web"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/posts\/1132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/comments?post=1132"}],"version-history":[{"count":0,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/posts\/1132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/media\/2767"}],"wp:attachment":[{"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/media?parent=1132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/categories?post=1132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comsentido.es\/ca\/wp-json\/wp\/v2\/tags?post=1132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}